{"id":2617,"date":"2022-11-08T14:24:56","date_gmt":"2022-11-08T13:24:56","guid":{"rendered":"http:\/\/iuexterior.org\/?p=2617"},"modified":"2022-11-08T14:25:14","modified_gmt":"2022-11-08T13:25:14","slug":"iu-exterior-considera-un-exito-la-i-escuela-de-otono-en-viena","status":"publish","type":"post","link":"https:\/\/iuexterior.org\/ca\/2022\/11\/08\/iu-exterior-considera-un-exito-la-i-escuela-de-otono-en-viena\/","title":{"rendered":"IU Exterior considera un \u00ab\u00e9xito\u00bb la I Escuela de Oto\u00f1o en Viena"},"content":{"rendered":"<h3 class=\"wp-block-heading\"><strong>La federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior) celebr\u00f3 su I Escuela de oto\u00f1o del 4 al 6 de noviembre reuniendo en Viena a representantes de la emigraci\u00f3n organizada para debatir el futuro de la agenda pol\u00edtica de las residentes en el extranjero.<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IU Exterior&nbsp;<\/strong>celebr\u00f3 su I Escuela de Oto\u00f1o en la sede de Transform! Europe y del Partido Comunista de Austria (KP\u00d6) reuniendo a militantes de la federaci\u00f3n llegados de diferentes lugares de Europa, miembros de organizaciones como el PCE, Podemos y movimientos sociales de la emigraci\u00f3n. Tambi\u00e9n miembros de diferentes Consejos de Residentes Espa\u00f1oles (CRE) y del Consejo General de la Ciudadan\u00eda Espa\u00f1ola en el Exterior (CGCEE).<br><br>La portavoz y coordinadora de IU Exterior,&nbsp;<strong>Nerea Fern\u00e1ndez Cordero<\/strong>, inaugur\u00f3 las jornadas, considerando que eran \u201cnecesarias tras a\u00f1os de pandemia y de no poder realizar eventos presenciales con gente llegada desde todas partes\u201d. Para Fern\u00e1ndez Cordero el objetivo de la Escuela de IU Exterior era \u201ccoger fuerza y definir la estrategia pol\u00edtica de los pr\u00f3ximos a\u00f1os, porque con la derogaci\u00f3n del voto rogado no se ha acabado la lucha y la emigraci\u00f3n tenemos a\u00fan mucho por lo que pelear\u201d. Luis Cort\u00e9s Barbado, portavoz de IU Global y residente en Viena, agradeci\u00f3 a \u201cTransform! Europe y al Partido Comunista de Austria su colaboraci\u00f3n para que las jornadas fueran posibles\u201d.<br><br><strong>Ismael Gonz\u00e1lez,<\/strong>&nbsp;Responsable de Organizaci\u00f3n de Izquierda Unida Federal, valor\u00f3 en su intervenci\u00f3n del viernes \u201cla situaci\u00f3n de la izquierda en la actualidad, con una fortaleza institucional, que sin embargo se da en un momento de debilidad en la sociedad, respecto a ciclos anteriores\u201d. No obstante, Gonz\u00e1lez consider\u00f3 que \u201cse est\u00e1 dando un cambio de tendencia y la movilizaci\u00f3n se est\u00e1 recuperando\u201d. Adem\u00e1s, puso de relieve la necesidad de mantener una estructuras fuertes, \u201cpara que nuestras organizaciones se conviertan en espacios seguros y en los que la gente pueda refugiarse en momentos duros\u201d. Adem\u00e1s, a\u00f1adi\u00f3 \u201clas sedes y espacios de IU tienen que ser algo m\u00e1s que salas de debate pol\u00edtico. Tienen que convertirse en lugares para crear comunidad..<br><br>La primera jornada de trabajo arranc\u00f3 el s\u00e1bado con mesas tem\u00e1ticas sobre la representaci\u00f3n pol\u00edtica de la poblaci\u00f3n en el exterior, haciendo \u00e9nfasis en la construcci\u00f3n de una futura circunscripci\u00f3n exterior.&nbsp;<strong>Christophe Premat,<\/strong>&nbsp;ex-diputado del Partido Socialista de Francia y experto en circunscripci\u00f3n exterior, explic\u00f3 los modelos de representaci\u00f3n pol\u00edtica que existen tanto en Francia, como en otros pa\u00edses como Portugal, Ecuador o Senegal. Por su parte,&nbsp;<strong>Juan Moreno Redondo,<\/strong>&nbsp;abogado de Izquierda Unida y del PCE, defini\u00f3 c\u00f3mo podr\u00eda ser el encaje legal para la creaci\u00f3n de una o varias circunscripciones en el Exterior, dentro del marco legal actualmente existente. Finalmente,&nbsp;<strong>Violeta Alonso Pel\u00e1ez<\/strong>, presidenta del Consejo General de la Ciudadan\u00eda Espa\u00f1ola en el Exterior, present\u00f3 cu\u00e1les son las funciones y composici\u00f3n de este \u00f3rgano, as\u00ed como la agenda pol\u00edtica que tiene por delante durante su mandato de esta octava legislatura del CGCEE.Por la tarde, se ahond\u00f3, en grupos de trabajo, en tres tem\u00e1ticas: la circunscripci\u00f3n exterior, la agenda pol\u00edtica de la emigraci\u00f3n y el internacionalismo de base. De esos debates salieron diversas propuestas, como el de trazar una primera idea de circunscripci\u00f3n exterior y la justificaci\u00f3n para su existencia; la necesidad de ampliar la agenda pol\u00edtica del exterior en asuntos como la mejora de las condiciones laborales y de recursos del servicio exterior, el reforzamiento de la asistencia consular, el trabajo sobre el retorno digno o el sistema educativo en el exterior; fortalecer el internacionalismo de base en un trabajo conjunto con redes migrantes de toda Europa, desde la idea de revolucionar el concepto de ciudadan\u00eda, que no est\u00e9 ligado a la nacionalidad, sino a un periodo de residencia (como sucede por ejemplo en Chile&nbsp; los cinco a\u00f1os), para que se otorguen derechos pol\u00edticos (voto) o laborales (eliminar necesidades de visados), como freno adem\u00e1s ante el avance del fascismo.<br><br>El domingo continu\u00f3 la escuela con las experiencias de otros colectivos migrantes organizados.&nbsp;<strong>Margarita Guerrero,<\/strong>&nbsp;de Revoluci\u00f3n Ciudadana (Ecuador) y de la Red de Migraciones de Izquierda Unida, habl\u00f3 de la organizaci\u00f3n de los colectivos migrantes en Espa\u00f1a y de la Iniciativa Legislativa Popular \u201c<a href=\"https:\/\/regularizacionya.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Regularizaci\u00f3n ya<\/a>\u201d, as\u00ed como de f\u00f3rmulas para fomentar la participaci\u00f3n pol\u00edtica de las migrantes en la sociedad en general y tambi\u00e9n en las organizaciones pol\u00edticas.&nbsp;<strong>V\u00edctor S\u00e1ez<\/strong>, co-coordinador de la Red europea de chilenos por los derechos c\u00edvicos y pol\u00edticos, traz\u00f3 la historia de la comunidad chilena en el exterior y su organizaci\u00f3n pol\u00edtica, desde el golpe de Estado contra Allende, hasta el proceso constituyente actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jaime Mart\u00ednez Porro,<\/strong>\u00a0co-responsable de Organizaci\u00f3n de IU Exterior, cerr\u00f3 la escuela recordando que \u201cIzquierda Unida es vuestra casa, se\u00e1is o no militantes. Las puertas de nuestra federaci\u00f3n est\u00e1n abiertas a todas las personas que quieran luchar por cambiar la sociedad y el sistema\u201d. As\u00ed, anim\u00f3 a seguir organiz\u00e1ndose y a seguir creando espacios de encuentro de la poblaci\u00f3n en el Exterior.<br><br>Finalmente, una vez acabada la\u00a0<strong>I Escuela de Oto\u00f1o\u00a0 IU Exterior<\/strong>\u00a0celebr\u00f3 un homenaje en el Cementerio Central de Viena a los y las brigadistas de Austria que combatieron al fascismo en Espa\u00f1a entre 1936 y 1939.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/IUExterior\/status\/1589281272568098817\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sobre IU Exterior<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Federaci\u00f3n del Exterior de Izquierda Unida<\/strong>&nbsp;<a href=\"http:\/\/iuexterior.org\/ca\/2017\/04\/30\/la-federacion-del-exterior-de-iu-nace-para-movilizar-politicamente-a-la-emigracion-espanola\/\">naci\u00f3 en abril de 2017<\/a>&nbsp;para movilizar pol\u00edticamente a la emigraci\u00f3n espa\u00f1ola y darle voz a sus reivindicaciones. Actualmente contamos con asambleas estables en&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Bruselas\/\">Bruselas<\/a>, B\u00e9lgica;&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Berlin\/\">Berl\u00edn<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Frankfurt\/\">Frankfurt<\/a>, en Alemania;&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Luexmburgo\/\">Luxemburgo<\/a>;&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Zurich\/\">Z\u00farich<\/a>, en Suiza; en&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Lyon\/\">Lyon<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Toulouse\/\">Toulouse<\/a>, en Francia; y tanto en la&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/BuenosAires\/\">Ciudad de Buenos Aires<\/a>&nbsp;como en la&nbsp;<a href=\"http:\/\/iuexterior.org\/ca\/provinciabuenosaires\/\">Provincia de Buenos Aires<\/a>, Argentina. Adem\u00e1s, la federaci\u00f3n dispone de la asamblea&nbsp;<a href=\"https:\/\/iuexterior.org\/ca\/Global\/\">IU Global<\/a>, por medio de la cual participa la militancia dispersa por el mundo sin acceso a una asamblea local propia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Pots contactar amb <strong>IU Exterior<\/strong> a trav\u00e9s del correu <a href=\"mailto:exterior@izquierdaunida.org\" rel=\"noreferrer noopener\" target=\"_self\"><strong>exterior@izquierdaunida.org<\/strong><\/a> o dels nostres perfils en <a href=\"https:\/\/www.facebook.com\/IUExterior\/\" rel=\"noreferrer noopener\" target=\"_self\"><strong>Facebook<\/strong><\/a>,\u00a0<a href=\"https:\/\/twitter.com\/IUExterior\/\" rel=\"noreferrer noopener\" target=\"_self\"><strong>Twitter<\/strong><\/a>\u00a0i\u00a0<a href=\"https:\/\/www.instagram.com\/IUExterior\/\" rel=\"noreferrer noopener\" target=\"_self\"><strong>Instagram<\/strong><\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>La federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior) celebr\u00f3 su I Escuela de oto\u00f1o del 4 al 6 de noviembre reuniendo en Viena a representantes de la emigraci\u00f3n &hellip;<\/p>","protected":false},"author":3,"featured_media":2618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[1,25,8,32,123],"tags":[],"class_list":["post-2617","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-actualidad","category-asambleas","category-destacado","category-federacion","category-formacion"],"_links":{"self":[{"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/2617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/comments?post=2617"}],"version-history":[{"count":4,"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/2617\/revisions"}],"predecessor-version":[{"id":2633,"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/2617\/revisions\/2633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/media\/2618"}],"wp:attachment":[{"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/media?parent=2617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/categories?post=2617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/tags?post=2617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}