{"id":2584,"date":"2022-05-02T14:48:24","date_gmt":"2022-05-02T12:48:24","guid":{"rendered":"http:\/\/iuexterior.org\/?p=2584"},"modified":"2022-05-02T14:48:25","modified_gmt":"2022-05-02T12:48:25","slug":"iu-bruselas-y-el-pce-en-belgica-respaldan-las-reivindicaciones-del-personal-laboral-en-el-consulado-general-de-espana-en-bruselas","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/gl\/2022\/05\/02\/iu-bruselas-y-el-pce-en-belgica-respaldan-las-reivindicaciones-del-personal-laboral-en-el-consulado-general-de-espana-en-bruselas\/","title":{"rendered":"IU Bruselas y el PCE en B\u00e9lgica respaldan las reivindicaciones del personal laboral en el Consulado General de Espa\u00f1a en Bruselas"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El jueves 28 de abril de 2022 el personal laboral en el Consulado General de Espa\u00f1a en Bruselas publicaba un <a href=\"https:\/\/mcusercontent.com\/fb3b3f2505de1afaf3d0d5c22\/files\/fd83670c-b68a-277e-fe6e-7ca0d3f4062b\/Comunicado_PLEX_Bruselas_28_abril_20222.pdf\">comunicado <\/a>mostrando su solidaridad con las movilizaciones y reivindicaciones que est\u00e1 llevando a cabo el personal laboral en Reino Unido, Alemania y Pa\u00edses Bajos, y denunciando \u201clas p\u00e9simas condiciones en las que tambi\u00e9n se ve obligado a trabajar el Personal Laboral en el Exterior de nuestro Consulado General y que le impiden poder prestar el servicio de calidad que la ciudadan\u00eda espa\u00f1ola en este pa\u00eds se merece.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la asamblea de<strong>&nbsp;Izquierda Unida en Bruselas y el n\u00facleo del PCE en B\u00e9lgica<\/strong>&nbsp;respaldamos tanto el comunicado como sus reivindicaciones. La<strong>&nbsp;federaci\u00f3n de IU Exterior<\/strong>&nbsp;como el&nbsp;<strong>PCE Exterior<\/strong>&nbsp;ya mostraron su solidaridad con el personal laboral en Reino Unida tras m\u00e1s de 45 d\u00edas de huelga, ya que los sucesivos gobiernos \u201chan incumplido de forma persistente y sigue ocurriendo el Estatuto de la Ciudadan\u00eda Espa\u00f1ola en el Exterior (Ley 40\/2006) en materia de protecci\u00f3n de la comunidad residente fuera de Espa\u00f1a\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>personal laboral en el Consulado General de Espa\u00f1a en Bruselas&nbsp;<\/strong>denuncia en el comunicado que \u201cm\u00e1s all\u00e1 de la congelaci\u00f3n de salarios, que se mantiene desde 2009 y les ha supuesto una p\u00e9rdida de poder adquisitivo de alrededor del 30%; del incumplimiento continuo de la ley belga, de aplicaci\u00f3n a los contratos de dicho personal (indexaci\u00f3n anual de los salarios, pago del transporte, pagas extras, compensaciones por trabajo efectuado en horario extraordinario); de las diferencias retributivas y de cobertura de seguridad social entre el personal de la misma categor\u00eda; del incumplimiento del derecho a la promoci\u00f3n profesional, impidiendo a este colectivo presentarse a candidaturas de promoci\u00f3n interna; de la exclusi\u00f3n del derecho a la acci\u00f3n social del que benefician el resto de empleados p\u00fablicos de la administraci\u00f3n espa\u00f1ola, etc.\u201d, se\u00f1alan,&nbsp;<strong>entre otras muchas cosas, las siguientes condiciones que obstaculizan el correcto funcionamiento de los servicios consulares de la administraci\u00f3n espa\u00f1ola en B\u00e9lgica:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Falta de recursos tanto humanos como t\u00e9cnicos (equipos inform\u00e1ticos desfasados, material insuficiente o que no es repuesto cuando se aver\u00eda\u2026) para dar servicio a una colonia de alrededor de 75000 espa\u00f1oles que no para de aumentar mientras los recursos no lo hacen.&nbsp;<\/strong>Por poner un ejemplo, mientras que en 1999 la plantilla era de 22 personas (sin contar al C\u00f3nsul y al Canciller) para una colonia de 38000 personas inscritas, hoy es de 20 empleados fijos y 1 temporal (m\u00e1s un diplom\u00e1tico que se suma al C\u00f3nsul y el Canciller que ya exist\u00edan) para una colonia de casi 75000 personas.<\/li><li><strong>Una oferta de servicios que se promete incluso por SMS pero que no se corresponde con la realidad de la fuerza de trabajo y de los medios de que dispone el Consulado para llevarlos a cabo.<\/strong><\/li><li><strong>Unas instalaciones anticuadas y obsoletas que ni siquiera cumplen con la ley por&nbsp;<\/strong>la que se establecen las condiciones de accesibilidad y no discriminaci\u00f3n de las personas con discapacidad en sus relaciones con la Administraci\u00f3n General del Estado.<\/li><li>Un&nbsp;<strong>sistema ineficaz para cubrir bajas por enfermedad o vacaciones<\/strong>&nbsp;resultado de una clara&nbsp;<strong>insuficiencia de recursos&nbsp;<\/strong>que no permite abarcar la demanda cuando la plantilla est\u00e1 completa, mucho menos cuando no lo est\u00e1.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, en el comunicado advierten:&nbsp;<strong>\u201cpor el momento, seguiremos ofreciendo nuestros servicios de la mejor manera que podamos a pesar de las dificultades. No obstante, si las condiciones no mejoran a pesar de las buenas palabras de los sindicatos y del Ministerio, no dudaremos en unirnos a las movilizaciones.\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde\u00a0<strong>IU\u00a0<\/strong>y el\u00a0<strong>PCE<\/strong>\u00a0en el Exterior piden que \u201cse atiendan y cumplan sus justas reivindicaciones para tener unas condiciones laborales y salarios dignos\u201d y reclaman al Gobierno que \u201ctome medidas urgentes, empezando por recibir a las personas que les representan\u00bb. Es necesario que se impliquen todos los ministerios que tienen alg\u00fan tipo de competencia en la gesti\u00f3n y administraci\u00f3n del Servicio Exterior, entre ellos, Asuntos Exteriores, Trabajo, Hacienda o Educaci\u00f3n\u201d.<br><br><strong>Desde IU Bruselas y el PCE en B\u00e9lgica animamos a la emigraci\u00f3n espa\u00f1ola a apoyar al personal de la administraci\u00f3n exterior en sus reivindicaciones. \u00a1Defendamos unos servicios p\u00fablicos de calidad tambi\u00e9n en el exterior!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"562\" src=\"http:\/\/iuexterior.org\/wp-content\/uploads\/2022\/05\/PLEX-1024x562.png\" alt=\"\" class=\"wp-image-2586\" srcset=\"http:\/\/iuexterior.org\/wp-content\/uploads\/2022\/05\/PLEX-1024x562.png 1024w, http:\/\/iuexterior.org\/wp-content\/uploads\/2022\/05\/PLEX-300x165.png 300w, http:\/\/iuexterior.org\/wp-content\/uploads\/2022\/05\/PLEX-768x422.png 768w, http:\/\/iuexterior.org\/wp-content\/uploads\/2022\/05\/PLEX-16x9.png 16w, http:\/\/iuexterior.org\/wp-content\/uploads\/2022\/05\/PLEX.png 1195w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>El jueves 28 de abril de 2022 el personal laboral en el Consulado General de Espa\u00f1a en Bruselas publicaba un comunicado mostrando su solidaridad con las movilizaciones y reivindicaciones que &hellip;<\/p>","protected":false},"author":3,"featured_media":2585,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[1,25,8,28],"tags":[],"class_list":["post-2584","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-actualidad","category-asambleas","category-destacado","category-iu-bruselas"],"_links":{"self":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts\/2584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/comments?post=2584"}],"version-history":[{"count":1,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts\/2584\/revisions"}],"predecessor-version":[{"id":2587,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts\/2584\/revisions\/2587"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/media\/2585"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/media?parent=2584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/categories?post=2584"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/tags?post=2584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}