{"id":2549,"date":"2021-09-16T16:59:53","date_gmt":"2021-09-16T14:59:53","guid":{"rendered":"http:\/\/iuexterior.org\/?p=2549"},"modified":"2021-09-16T16:59:55","modified_gmt":"2021-09-16T14:59:55","slug":"iu-exterior-abre-desde-hoy-el-proceso-de-votaciones-de-los-documentos-de-cara-a-su-ii-asamblea-de-federacion","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/gl\/2021\/09\/16\/iu-exterior-abre-desde-hoy-el-proceso-de-votaciones-de-los-documentos-de-cara-a-su-ii-asamblea-de-federacion\/","title":{"rendered":"IU Exterior abre desde hoy el proceso de votaciones de los documentos de cara a su II Asamblea de Federaci\u00f3n"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>La militancia de IU Exterior est\u00e1<\/strong> <strong>llamada desde hoy a las 17h00 (hora peninsular) y hasta el domingo 19 de septiembre a participar en la votaci\u00f3n telem\u00e1tica y presencial de los documentos pol\u00edtico organizativo y los estatutos, as\u00ed como la \u00fanica lista presentada \u201cEn todas partes, IU Exterior\u201d, en vista a su II Asamblea de Federaci\u00f3n que se celebra el s\u00e1bado 2 de octubre.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IU Exterior<\/strong> ha dado comienzo, siguiendo el <a href=\"http:\/\/iuexterior.org\/wp-content\/uploads\/2021\/07\/93103790-354e-4b85-b926-da7db74e116d.pdf\">calendario <\/a>aprobado por la Coordinadora el pasado 15 de julio, al plazo de votaciones que culminar\u00e1 con la celebraci\u00f3n de su segunda Asamblea de Federaci\u00f3n. La militancia participa en este proceso de votaciones tras haber debatido los documentos y presentado las enmiendas correspondientes en sus asambleas de base.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nerea Fern\u00e1ndez Cordero<\/strong>, co-coordinadora de <strong>IU Exterior<\/strong>, recalca \u201cque, aunque el nuevo curso pol\u00edtico arranca en septiembre, la militancia de IU Exterior ha continuado trabajando durante el par\u00f3n veraniego y las asambleas de base han podido debatir los documentos presentados de cara a la II Asamblea de Federaci\u00f3n\u201d y recuerda que \u201cadem\u00e1s, cada asamblea ha elegido a los y las delegadas que participar\u00e1n el pr\u00f3ximo 2 de octubre.\u201d\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde <strong>IU Exterior <\/strong>recuerdan que la II Asamblea de Federaci\u00f3n marca el proceso de debate para conseguir avanzar en los objetivos de la federaci\u00f3n y a la que todas las militantes y simpatizantes est\u00e1n invitadas a participar a trav\u00e9s de sus asambleas. \u201cLa voz de cada una de las personas que formamos esta organizaci\u00f3n es necesaria para poder seguir construyendo IU Exterior, una organizaci\u00f3n que pone en el centro del debate las problem\u00e1ticas de la emigraci\u00f3n\u201d recuerda <strong>Jaime Mart\u00ednez,<\/strong> corresponsable de Organizaci\u00f3n de la federaci\u00f3n.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fern\u00e1ndez Cordero<\/strong> anima a la militancia a participar en las votaciones y a\u00f1ade que \u201cesperamos veros el pr\u00f3ximo 2 de octubre y as\u00ed poder finalizar este proceso que estamos teniendo y que est\u00e1 siendo bastante enriquecedor\u201d .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los documentos de debate de la II Asamblea de IU Exterior est\u00e1n disponibles en la\u00a0<a href=\"http:\/\/iuexterior.org\/gl\/ii-asamblea-iu-exterior\/\">p\u00e1gina web<\/a>\u00a0de la Federaci\u00f3n.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">                          <a href=\"https:\/\/militancia.izquierdaunida.org\/\">>> PARTICIPA &lt;&lt;<\/a><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/IUExterior\/status\/1437448099551715328\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Acerca de IU Exterior<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Federaci\u00f3n del Exterior de Izquierda Unida<\/strong>&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/2017\/04\/30\/la-federacion-del-exterior-de-iu-nace-para-movilizar-politicamente-a-la-emigracion-espanola\/\">naci\u00f3 en abril de 2017<\/a>&nbsp;para movilizar pol\u00edticamente a la emigraci\u00f3n espa\u00f1ola y darle voz a sus reivindicaciones. Actualmente contamos con asambleas estables en&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Bruselas\/\">Bruselas<\/a>, B\u00e9lgica;&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Berlin\/\">Berl\u00edn<\/a>&nbsp;y&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Frankfurt\/\">Frankfurt<\/a>, en Alemania;&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Luexmburgo\/\">Luxemburgo<\/a>;&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Zurich\/\">Z\u00farich<\/a>, en Suiza; en&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Lyon\/\">Lyon<\/a>&nbsp;y&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Toulouse\/\">Toulouse<\/a>, en Francia; y tanto en la&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/BuenosAires\/\">Ciudad de Buenos Aires<\/a>&nbsp;como en la&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/provinciabuenosaires\/\">Provincia de Buenos Aires<\/a>, Argentina. Adem\u00e1s, la federaci\u00f3n dispone de la asamblea&nbsp;<a href=\"http:\/\/iuexterior.org\/gl\/Global\/\">IU Global<\/a>, por medio de la cual participa la militancia dispersa por el mundo sin acceso a una asamblea local propia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Puedes contactar con&nbsp;<strong>IU Exterior<\/strong>&nbsp;a trav\u00e9s del correo&nbsp;<a href=\"mailto:exterior@izquierdaunida.org\" rel=\"noreferrer noopener\" target=\"_self\"><strong>exterior@izquierdaunida.org<\/strong><\/a>&nbsp;o de nuestros perfiles en&nbsp;<a href=\"https:\/\/www.facebook.com\/IUExterior\/\" rel=\"noreferrer noopener\" target=\"_self\"><strong>Facebook<\/strong><\/a>,&nbsp;<a href=\"https:\/\/twitter.com\/IUExterior\/\" rel=\"noreferrer noopener\" target=\"_self\"><strong>Twitter<\/strong><\/a>&nbsp;e&nbsp;<a href=\"https:\/\/www.instagram.com\/IUExterior\/\" rel=\"noreferrer noopener\" target=\"_self\"><strong>Instagram<\/strong><\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>La militancia de IU Exterior est\u00e1 llamada desde hoy a las 17h00 (hora peninsular) y hasta el domingo 19 de septiembre a participar en la votaci\u00f3n telem\u00e1tica y presencial de &hellip;<\/p>","protected":false},"author":3,"featured_media":2489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[1,8,32],"tags":[],"class_list":["post-2549","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-actualidad","category-destacado","category-federacion"],"_links":{"self":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts\/2549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/comments?post=2549"}],"version-history":[{"count":3,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts\/2549\/revisions"}],"predecessor-version":[{"id":2552,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/posts\/2549\/revisions\/2552"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/media\/2489"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/media?parent=2549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/categories?post=2549"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/gl\/wp-json\/wp\/v2\/tags?post=2549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}