{"id":819,"date":"2018-11-30T11:00:14","date_gmt":"2018-11-30T10:00:14","guid":{"rendered":"http:\/\/iuexterior.org\/?p=819"},"modified":"2020-04-30T08:15:07","modified_gmt":"2020-04-30T06:15:07","slug":"el-coportavoz-de-iu-exterior-eduardo-velazquez-visita-argentina-y-uruguay-para-presentar-la-ley-de-nacionalidad-para-descendientes","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/eu\/2018\/11\/30\/el-coportavoz-de-iu-exterior-eduardo-velazquez-visita-argentina-y-uruguay-para-presentar-la-ley-de-nacionalidad-para-descendientes\/","title":{"rendered":"El coportavoz de IU Exterior Eduardo Vel\u00e1zquez visita Argentina y Uruguay para presentar la Ley de Nacionalidad para Descendientes"},"content":{"rendered":"<h4><span style=\"font-weight: 400;\">El responsable de la Federaci\u00f3n del Exterior de Izquierda Unida se reuni\u00f3 con diversos colectivos de la emigraci\u00f3n espa\u00f1ola, <\/span><span style=\"font-weight: 400;\">sindicatos y fuerzas pol\u00edticas.<\/span><\/h4>\n<p><b>Eduardo Vel\u00e1zquez<\/b><span style=\"font-weight: 400;\">, coportavoz de la Federaci\u00f3n de <\/span><b>Izquierda Unida<\/b><span style=\"font-weight: 400;\"> en el Exterior (<\/span><b>IU Exterior<\/b><span style=\"font-weight: 400;\">), visit\u00f3 las ciudades de Buenos Aires y Rosario (Argentina), y la capital de Uruguay, Montevideo, <\/span><b>del 1 al 9 de diciembre<\/b><span style=\"font-weight: 400;\"> para mantener diversos encuentros con colectivos de la emigraci\u00f3n espa\u00f1ola y presentar la <\/span><i><span style=\"font-weight: 400;\">proposici\u00f3n de ley en materia de concesi\u00f3n de la nacionalidad espa\u00f1ola a los descendientes nacidos en el extranjero de progenitores espa\u00f1oles<\/span><\/i><span style=\"font-weight: 400;\"> (Ley de Nacionalidad para Descendientes), <\/span><a href=\"http:\/\/iuexterior.org\/eu\/2018\/06\/19\/el-senado-admite-a-tramite-la-ley-de-nacionalidad-para-descendientes-de-espanoles\/\"><span style=\"font-weight: 400;\">admitida a tr\u00e1mite<\/span><\/a><span style=\"font-weight: 400;\"> en junio de este mismo a\u00f1o, en el Senado, con el voto a favor de todos los grupos.<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Eduardo Vel\u00e1zquez y Sara Vil\u00e0 presentan la Ley de Descendientes en Buenos Aires\" width=\"618\" height=\"348\" src=\"https:\/\/www.youtube.com\/embed\/Mwf-Qs2PNI4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><b>IU Exterior<\/b> <a href=\"http:\/\/iuexterior.org\/eu\/2018\/05\/23\/iu-exterior-defiende-la-concesion-de-nacionalidad-a-descendientes-de-espanoles-en-el-2o-congreso-de-nacionalidad-espanola\/\"><span style=\"font-weight: 400;\">ha apoyado desde el principio<\/span><\/a><span style=\"font-weight: 400;\"> la tramitaci\u00f3n de la Ley de Nacionalidad para Descendientes, que tiene como objetivo fundamental favorecer el acceso a la nacionalidad espa\u00f1ola de los cuatro perfiles de personas que hab\u00edan quedado excluidas bajo la reforma de Ley de Memoria Hist\u00f3rica: los nietos y nietas de espa\u00f1olas casadas con un no espa\u00f1ol antes de 1978, que quedaron impedidas para transmitir la nacionalidad; los nietos y nietas de espa\u00f1oles nacionalizados en el pa\u00eds de acogida por cuestiones econ\u00f3micas, que estaban obligados a renunciar a su nacionalidad; y los nietos y nietas de espa\u00f1oles que no ratificaron su deseo de conservar la nacionalidad a los 18 a\u00f1os; y por \u00faltimo, los hijos e hijas mayores de edad de quienes obtuvieron la nacionalidad acogi\u00e9ndose a la Ley de Memoria Hist\u00f3rica.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Siguiendo una ajustada agenda coordinada con la asamblea de <\/span><b>IU en Buenos Aires<\/b><span style=\"font-weight: 400;\">, el coportavoz de <\/span><b>IU Exterior<\/b><span style=\"font-weight: 400;\"> se reuni\u00f3 con los responsables del Centro de Descendientes de Espa\u00f1oles Unidos (Cedeu) -colectivo que ha participado activamente en la elaboraci\u00f3n de la ley-, as\u00ed como con otras organizaciones como la agrupaci\u00f3n Federico Garc\u00eda Lorca, la Comisi\u00f3n de Espa\u00f1oles Desaparecidos en Argentina, los y las querellantes por delitos de lesa humanidad cometidos en el franquismo, el Club Deportivo Espa\u00f1ol, el Consejo de Residentes de Espa\u00f1oles de Montevideo y Buenos Aires, el Centro Betanzos o el Club Espa\u00f1ol de Rosario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Asimismo, <\/span><b>Vel\u00e1zquez <\/b><span style=\"font-weight: 400;\">aprovech\u00f3 la ocasi\u00f3n para confraternizar con otras organizaciones pol\u00edticas como el Partido Comunista de la Argentina; los c\u00edrculos de Podemos en Uruguay y Buenos Aires; Socialismo para la Victoria; la Fuerza de Orientaci\u00f3n Radical de la Joven Argentina (Forja); Los Irrompibles; as\u00ed como con los y las representantes sindicales del Servicio Exterior &#8211;<\/span><a href=\"http:\/\/iuexterior.org\/eu\/2018\/09\/05\/iu-exterior-solicita-una-reunion-con-los-nuevos-responsables-de-hacienda-y-funcion-publica-para-encontrar-una-solucion-a-la-situacion-del-personal-laboral-del-servicio-exterior\/\"><span style=\"font-weight: 400;\">cuya situaci\u00f3n laboral viene denunciando IU Exterior desde hace algo m\u00e1s de un a\u00f1o<\/span><\/a><span style=\"font-weight: 400;\">&#8211; y de la Central de Trabajadores de la Argentina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En relaci\u00f3n con este viaje, el coportavoz de <\/span><b>IU Exterior <\/b>declar\u00f3&nbsp;<span style=\"font-weight: 400;\">que \u201cBuenos Aires, Montevideo y Rosario, as\u00ed como otras ciudades de Am\u00e9rica Latina, son lugares profundamente marcados por la emigraci\u00f3n espa\u00f1ola en general y el exilio republicano en particular. Cualquier fuerza pol\u00edtica que aspire a la construcci\u00f3n de un nuevo pa\u00eds debe tener en cuenta las demandas, as\u00ed como la herencia cultural y pol\u00edtica de las personas que formaron parte de esta di\u00e1spora y sus descendientes\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El viaje se enmarc\u00f3 en el contexto de la visita realizada tambi\u00e9n por la senadora <\/span><b>Sara Vil\u00e1<\/b><span style=\"font-weight: 400;\"> (<\/span><b>Unidos Podemos-En Com\u00fa Podem-En Marea<\/b><span style=\"font-weight: 400;\">), involucrada activamente en la tramitaci\u00f3n de la Ley de Nacionalidad para Descendientes. Recientemente, <\/span><b>IU Exterior<\/b><span style=\"font-weight: 400;\"> alertaba de que dicha ley, que actualmente se encuentra en proceso de enmiendas, <\/span><a href=\"http:\/\/iuexterior.org\/eu\/2018\/11\/06\/iu-exterior-exige-al-psoe-que-retire-sus-enmiendas-a-la-ley-de-nacionalidad-para-descendientes-para-evitar-dejarla-sin-efecto\/\"><span style=\"font-weight: 400;\">corr\u00eda peligro de quedarse sin efecto<\/span><\/a><span style=\"font-weight: 400;\"> debido a la nueva redacci\u00f3n de los art\u00edculos 17, 20 y 26 del C\u00f3digo Civil propuesta por el grupo socialista, que dejaba los requisitos de acceso redactados de una manera mucho m\u00e1s ambigua.<\/span><\/p>\n<h3>Kanpoko IUri buruz<\/h3>\n<p>La&nbsp;<b>Federaci\u00f3n del Exterior de Izquierda Unida<\/b>&nbsp;<a href=\"http:\/\/iuexterior.org\/eu\/2017\/04\/30\/la-federacion-del-exterior-de-iu-nace-para-movilizar-politicamente-a-la-emigracion-espanola\/\">naci\u00f3 en abril de 2017<\/a>&nbsp;para movilizar pol\u00edticamente a la emigraci\u00f3n espa\u00f1ola y darle voz a sus reivindicaciones. Actualmente contamos con asambleas estables en&nbsp;<a href=\"https:\/\/www.facebook.com\/IUBruselas\/\">Bruselas<\/a>, B\u00e9lgica;&nbsp;<a href=\"https:\/\/www.facebook.com\/iuberlin\/\">Berl\u00edn<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/www.facebook.com\/iufrankfurt\/\">Frankfurt<\/a>, en Alemania;&nbsp;<a href=\"https:\/\/www.facebook.com\/IzquierdaUnidaLuxemburgo\/\">Luxemburgo<\/a>;&nbsp;<a href=\"https:\/\/www.facebook.com\/IUZurich\/\">Z\u00farich<\/a>, en Suiza; en&nbsp;<a href=\"https:\/\/www.facebook.com\/izquierdaunidalyon\/\">Lyon<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/www.facebook.com\/IUToulouse\/\">Toulouse<\/a>, en Francia; y en&nbsp;<a href=\"https:\/\/www.facebook.com\/iuBuenosAires\/\">Buenos Aires<\/a>, Argentina.<\/p>","protected":false},"excerpt":{"rendered":"<p>El responsable de la Federaci\u00f3n del Exterior de Izquierda Unida se reuni\u00f3 con diversos colectivos de la emigraci\u00f3n espa\u00f1ola, sindicatos y fuerzas pol\u00edticas. Eduardo Vel\u00e1zquez, coportavoz de la Federaci\u00f3n de &hellip;<\/p>","protected":false},"author":3,"featured_media":835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[110,1,25,8,32,29,112,118],"tags":[],"class_list":["post-819","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-acciones","category-actualidad","category-asambleas","category-destacado","category-federacion","category-iu-buenos-aires","category-ley-de-descendientes","category-memoria-democratica"],"_links":{"self":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts\/819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":4,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"predecessor-version":[{"id":1746,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts\/819\/revisions\/1746"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/media\/835"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}