{"id":443,"date":"2018-05-23T16:20:55","date_gmt":"2018-05-23T14:20:55","guid":{"rendered":"http:\/\/iuexterior.org\/?p=443"},"modified":"2020-04-29T23:02:51","modified_gmt":"2020-04-29T21:02:51","slug":"iu-exterior-defiende-la-concesion-de-nacionalidad-a-descendientes-de-espanoles-en-el-2o-congreso-de-nacionalidad-espanola","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/eu\/2018\/05\/23\/iu-exterior-defiende-la-concesion-de-nacionalidad-a-descendientes-de-espanoles-en-el-2o-congreso-de-nacionalidad-espanola\/","title":{"rendered":"IU Exterior defiende la concesi\u00f3n de nacionalidad a descendientes de espa\u00f1oles en el 2\u00ba Congreso de Nacionalidad Espa\u00f1ola"},"content":{"rendered":"<h4><strong>El portavoz de IU Exterior, Eduardo Vel\u00e1zquez, defendi\u00f3 la Proposici\u00f3n de Ley como una \u00abnecesidad social\u00bb y una \u00abcuesti\u00f3n de justicia\u00bb<\/strong><\/h4>\n<p>Los participantes en el seminario sobre la Proposici\u00f3n de Ley en materia de concesi\u00f3n de nacionalidad espa\u00f1ola a los descendientes nacidos en el extranjero de espa\u00f1oles, celebrado en el marco del 2\u00ba Congreso de Nacionalidad Espa\u00f1ola -seg\u00fan <a href=\"http:\/\/www.cronicasdelaemigracion.com\/articulo\/cronicas\/2o-congreso-nacionalidad-espanola-denuncia-carencias-ley-memoria-historica\/20180522083224086515.html\">Cr\u00f3nicas de la Emigraci\u00f3n<\/a>-, abordaron los fallos en la ley de Memoria Hist\u00f3rica de la mano de <strong>Danthe Menes<\/strong>, doctor en Derecho y Ciencia Pol\u00edtica y asesor de Inmigraci\u00f3n en Sagardoy Abogados, que se\u00f1al\u00f3 la gran cifra que supone la di\u00e1spora espa\u00f1ola en el exterior: \u201cSon 1,8 millones de espa\u00f1oles fuera del pa\u00eds y hay 275.000 descendientes de espa\u00f1oles que no han podido acceder a la nacionalidad espa\u00f1ola\u201d.<\/p>\n<p>Seg\u00fan <em>Cr\u00f3nicas<\/em>, teniendo estos datos en cuenta, denunci\u00f3 las carencias que tiene la Ley de Memoria Hist\u00f3rica, que impide conceder la nacionalidad en cuatro supuestos: a los nietos de mujeres espa\u00f1olas casadas con un no espa\u00f1ol antes de 1938, algo que \u201csupone una discriminaci\u00f3n por sexo porque las mujeres no ten\u00edan derecho a dar en herencia la nacionalidad\u201d; pero tambi\u00e9n quedan a un lado los hijos mayores de edad de las personas que obtuvieron la nacionalidad de origen; los nietos de los espa\u00f1oles que se vieron obligados a emigrar y a aceptar la nacionalidad del pa\u00eds de destino, cuyos hijos y nietos \u201cya no son espa\u00f1oles porque sus padres se han nacionalizado en otro pa\u00eds\u201d; y espa\u00f1oles que, ostentando la nacionalidad no la han ratificado con el tiempo y la perd\u00edan.<\/p>\n<p>Menes, recoge <em>Cr\u00f3nicas<\/em>, explic\u00f3 su trabajo con los partidos pol\u00edticos, a los que ha solicitado revisar esta ley para impulsar una nueva que recoja todos los supuestos sin ning\u00fan tipo de discriminaci\u00f3n como tienen otros pa\u00edses como Italia o Portugal, a la vez que mand\u00f3 un mensaje al Gobierno: \u201cEspa\u00f1a ha sido siempre un lugar de inmigrantes y eso es algo que el gobierno tendr\u00eda que tener en cuenta y no dar la espalda a estos descendientes en el exterior\u201d.<\/p>\n<p>Tambi\u00e9n <strong>Eduardo Vel\u00e1zquez<\/strong>, coordinador de la <strong>Federaci\u00f3n de Exterior de Izquierda Unida<\/strong>, se refiri\u00f3 a estos cuatro supuestos y, siguiendo la idea de Menes, asegur\u00f3 que \u00abEspa\u00f1a se ha dejado una parte muy importante de s\u00ed misma fuera de sus fronteras\u201d con esta ley. \u00c9ste, como representante pol\u00edtico, defendi\u00f3 el respaldo de su partido a esta Proposici\u00f3n de Ley porque \u00abes una cuesti\u00f3n de justicia garantizar la nacionalidad de quienes huyeron de nuestro pa\u00eds escapando de la miseria y la persecuci\u00f3n pol\u00edtica\u201d. Vel\u00e1zquez asegur\u00f3 que \u201cseg\u00fan el INE, 76.197 personas se registraron en el PERE durante 2017, luego la emigraci\u00f3n espa\u00f1ola sigue aumentando. Y eso es s\u00f3lo una parte, porque mucha gente no se inscribe en los consulados\u201d. Si bien lament\u00f3 que en a\u00f1o y medio no se haya conseguido llevar a votaci\u00f3n la nueva ley, conf\u00eda en que tarde o temprano se lleve a cabo porque \u201cel hecho de garantizar la nacionalidad espa\u00f1ola a m\u00e1s personas garantizar\u00eda un crecimiento social, econ\u00f3mico y vitales para la Espa\u00f1a del futuro\u201d.<\/p>\n<p>Por su parte, menciona <em>Cr\u00f3nicas<\/em>, la catedr\u00e1tica en Derecho Internacional Privado <strong>Aurelia \u00c1lvarez<\/strong> record\u00f3 en su intervenci\u00f3n que la primera ley de Inmigraci\u00f3n en Espa\u00f1a naci\u00f3 en 1971 y la \u00faltima data de 2006. \u201cEntre ese tiempo solo ha habido parches en el C\u00f3digo Civil\u201d, se\u00f1al\u00f3. \u00c1lvarez tambi\u00e9n particip\u00f3 en la mesa redonda \u2018La nacionalidad Espa\u00f1ola, materia en constante movimiento\u2019, que clausur\u00f3 el Congreso y en la que estuvo <strong>Guillermo Morales<\/strong>, CEO de Legal Team; junto a <strong>Carlos Mateo<\/strong>, abogado del ICAM, y <strong>Rosa Dur\u00e1n<\/strong>, letrada de ICAH.<\/p>\n<p>Este Congreso, organizado por la Asociaci\u00f3n de Inmigrantes sin Fronteras y el Grupo Aristeo, ha concentrado a un centenar de personas con el objetivo de dar a conocer las novedades en todo lo relacionado a la obtenci\u00f3n de la nacionalidad espa\u00f1ola.<\/p>\n<p><em><strong>Kanpoko IUri buruz<\/strong><\/em><\/p>\n<p>La Federaci\u00f3n del Exterior de Izquierda Unida naci\u00f3 en abril de 2017 para movilizar pol\u00edticamente a la emigraci\u00f3n espa\u00f1ola y darle voz a sus reivindicaciones. Actualmente contamos con asambleas estables en Bruselas, B\u00e9lgica; Berl\u00edn y Frankfurt, en Alemania; Luxemburgo; Z\u00farich, en Suiza; en Lyon, Toulouse y Montpellier, en Francia; y en Buenos Aires, Argentina.<\/p>\n<p>Para contactar con IU Exterior env\u00edanos un mail a: <strong>exterior@izquierdaunida.org<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>El portavoz de IU Exterior, Eduardo Vel\u00e1zquez, defendi\u00f3 la Proposici\u00f3n de Ley como una \u00abnecesidad social\u00bb y una \u00abcuesti\u00f3n de justicia\u00bb Los participantes en el seminario sobre la Proposici\u00f3n de &hellip;<\/p>","protected":false},"author":1,"featured_media":444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[110,1,8,4,112],"tags":[12,13,20,23],"class_list":["post-443","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-acciones","category-actualidad","category-destacado","category-documentos","category-ley-de-descendientes","tag-emigracion","tag-iuexterior","tag-memoria","tag-nacionalidad"],"_links":{"self":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts\/443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":4,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts\/443\/revisions"}],"predecessor-version":[{"id":449,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/posts\/443\/revisions\/449"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/media\/444"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/categories?post=443"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/eu\/wp-json\/wp\/v2\/tags?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}