{"id":1516,"date":"2020-02-10T08:29:02","date_gmt":"2020-02-10T07:29:02","guid":{"rendered":"http:\/\/iuexterior.org\/?p=1516"},"modified":"2020-04-30T11:04:35","modified_gmt":"2020-04-30T09:04:35","slug":"la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/en\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/","title":{"rendered":"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid"},"content":{"rendered":"<p class=\"has-medium-font-size\">Descendiente de familia espa\u00f1ola y militante de Izquierda Unida en Buenos Aires, Moura ha mantenido reuniones con diputados de Unidas Podemos en el Congreso y con la oficina local de Izquierda Unida en el Parlamento Europeo, entre otras.<\/p>\n\n\n\n<p><em>\u00abEs necesario agilizar la tramitaci\u00f3n de la Ley de Descendientes para favorecer el acceso a la nacionalidad espa\u00f1ola a aquellos perfiles que quedaron excluidos con la reforma de la Ley de Memoria Hist\u00f3rica\u00bb<\/em>, manifest\u00f3 la <strong>corresponsable de Acci\u00f3n Pol\u00edtica de Izquierda Unida en el Exterior (IU Exterior) Pilar Moura<\/strong>, en una reuni\u00f3n el <strong>martes, 4 de febrero<\/strong>, con los diputados de <strong>Unidas Podemos Enrique Santiago y Txema Guijarro<\/strong>, el <strong>Centro de Descendientes Espa\u00f1oles Unidos (CeDEU)<\/strong>, el <strong>secretario de Memoria Democr\u00e1tica del Partido Comunista de Espa\u00f1a (PCE), Mauricio Valiente<\/strong>, y el <strong>coportavoz de IU Exterior, Eduardo Vel\u00e1zquez<\/strong>. Militante de la asamblea de <strong>IU Buenos Aires <\/strong>y descendiente de familia espa\u00f1ola, <strong>Moura <\/strong>ha concluido esta semana una serie de encuentros con colectivos sociales y agentes pol\u00edticos en <strong>Madrid<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/IUExterior\/status\/1224679662506446849\n<\/div><\/figure>\n\n\n\n<p>La  Proposici\u00f3n de Ley de Nacionalidad para Descendientes, impulsada por <strong>Unidas Podemos e IU Exterior<\/strong>, fue admitida a tr\u00e1mite en el Senado <a href=\"http:\/\/La iniciativa, defendida por Unidos Podemos, el Ce.DEU e IU Exterior, abre la puerta a la reparaci\u00f3n de situaciones injustas ante la falta de reconocimiento de la nacionalidad espa\u00f1ola para determinados descendientes. El Senado ha aprobado este lunes, 18 de junio, la admisi\u00f3n a tr\u00e1mite de una Proposici\u00f3n de Ley de Unidos Podemos \u2013 En Com\u00fa Podem \u2013 En Marea en materia de concesi\u00f3n de la nacionalidad espa\u00f1ola a los descendientes de progenitores espa\u00f1oles nacidos en el extranjero. La proposici\u00f3n, impulsada por la senadora de En Com\u00fa Podem Sara Vil\u00e0, ha sido admitida a tr\u00e1mite con el voto positivo de todos los grupos parlamentarios de la C\u00e1mara Alta.\">en junio de 2018<\/a> con el voto positivo de todos los grupos parlamentarios de la C\u00e1mara Alta. En el encuentro, los responsables de <strong>Unidas Podemos<\/strong> trasladaron su apoyo y su voluntad para conseguir su tramitaci\u00f3n con celeridad.<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Hoy nos hemos reunido en el Congreso con una representacion del Centro de Descendientes Espa\u00f1oles Unidos <a href=\"https:\/\/twitter.com\/CeDEU2?ref_src=twsrc%5Etfw\">@CeDEU2<\/a>.<br><br>Hemos trasladado el total apoyo de <a href=\"https:\/\/twitter.com\/hashtag\/UnidasPodemos?src=hash&amp;ref_src=twsrc%5Etfw\">#UnidasPodemos<\/a> a su demanda de agilizar la tramitaci\u00f3n de la <a href=\"https:\/\/twitter.com\/hashtag\/LeyDeDescendientes?src=hash&amp;ref_src=twsrc%5Etfw\">#LeyDeDescendientes<\/a>. <a href=\"https:\/\/t.co\/WJgeK6ZhEt\">pic.twitter.com\/WJgeK6ZhEt<\/a><\/p>&mdash; Enrique Santiago (@EnriqueSantiago) <a href=\"https:\/\/twitter.com\/EnriqueSantiago\/status\/1224675977697071105?ref_src=twsrc%5Etfw\">February 4, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>La iniciativa tiene como objetivo fundamental <a href=\"http:\/\/iuexterior.org\/en\/2018\/05\/23\/iu-exterior-defiende-la-concesion-de-nacionalidad-a-descendientes-de-espanoles-en-el-2o-congreso-de-nacionalidad-espanola\/\">favorecer el acceso a la nacionalidad espa\u00f1ola<\/a> de los cuatro perfiles de personas que hab\u00edan quedado excluidas bajo la reforma de Ley de Memoria Hist\u00f3rica: los nietos y nietas de espa\u00f1olas casadas con un no espa\u00f1ol antes de 1978, que quedaron impedidas para transmitir la nacionalidad; los nietos y nietas de espa\u00f1oles nacionalizados en el pa\u00eds de acogida por cuestiones econ\u00f3micas, que estaban obligados a renunciar a su nacionalidad; y los nietos y nietas de espa\u00f1oles que no ratificaron su deseo de conservar la nacionalidad a los 18 a\u00f1os; y por \u00faltimo, los hijos e hijas mayores de edad de quienes obtuvieron la nacionalidad acogi\u00e9ndose a la Ley de Memoria Hist\u00f3rica.<\/p>\n\n\n\n<figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-instagram\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/p\/B8Lf5Xqle3Q\/\n<\/div><\/figure>\n\n\n\n<p>Otro de los encuentros tuvo lugar el <strong>jueves, 6 de febrero<\/strong>, con la <strong>coordinadora de la oficina local de IU en el Parlamento Europeo, Mar\u00eda Mart\u00ednez<\/strong>, con el objetivo de abordar diferentes problem\u00e1ticas que afectan a la emigraci\u00f3n, como son como la <a href=\"http:\/\/iuexterior.org\/en\/2018\/06\/08\/iu-exterior-le-exige-al-nuevo-gobierno-la-derogacion-del-voto-rogado-y-que-promueva-las-condiciones-para-el-retorno-digno-de-la-emigracion-espanola\/\">derogaci\u00f3n del voto rogado<\/a>, la implantaci\u00f3n <a href=\"http:\/\/iuexterior.org\/en\/2019\/04\/08\/ayuntamientos-con-representacion-de-iu-promueven-mociones-para-un-retorno-digno-de-la-emigracion\/\">planes de retorno digno<\/a>, la <a href=\"http:\/\/iuexterior.org\/en\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/\">vulneraci\u00f3n de derechos laborales<\/a> y sanitarios en el extranjero o la ya citada Ley de Nacionalidad.<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/IUExterior\/status\/1225474604384313346\n<\/div><\/figure>\n\n\n\n<p>Adem\u00e1s, durante su visita a la capital, <strong>la corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior<\/strong> ha tenido la oportunidad de visitar <strong>junto al coportavoz de IU Exterior<\/strong> la <a rel=\"noreferrer noopener\" aria-label=\"Red Solidaria Popular Latina-Carabanchel (se abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.reddesolidaridadpopular.org\/red\/latina-carabanchel\" target=\"_blank\">Red Solidaria Popular Latina-Carabanchel<\/a>, en palabras de <strong>Vel\u00e1zquez<\/strong>, <em>\u00abun proyecto de solidaridad, apoyo mutuo, construcci\u00f3n de lazos sociales y empoderamiento entre trabajadoras\u00bb<\/em>. <\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/IUExterior\/status\/1224614321294102528\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">About United Left Abroad<\/h2>\n\n\n\n<p>La&nbsp;<strong>Federaci\u00f3n del Exterior de Izquierda Unida&nbsp;<\/strong><a href=\"http:\/\/iuexterior.org\/en\/2017\/04\/30\/la-federacion-del-exterior-de-iu-nace-para-movilizar-politicamente-a-la-emigracion-espanola\/\">naci\u00f3 en abril de 2017<\/a>&nbsp;para movilizar pol\u00edticamente a la emigraci\u00f3n espa\u00f1ola y darle voz a sus reivindicaciones. Actualmente contamos con asambleas estables en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUBruselas\/\" target=\"_blank\">Bruselas<\/a>, B\u00e9lgica;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iuberlin\/\" target=\"_blank\">Berl\u00edn<\/a>&nbsp;and&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iufrankfurt\/\" target=\"_blank\">Frankfurt<\/a>, en Alemania;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IzquierdaUnidaLuxemburgo\/\" target=\"_blank\">Luxemburgo<\/a>;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUZurich\/\" target=\"_blank\">Z\u00farich<\/a>, en Suiza; en&nbsp;<a href=\"https:\/\/www.facebook.com\/izquierdaunidalyon\/\">Lyon<\/a>,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUToulouse\/\" target=\"_blank\">Toulouse<\/a>&nbsp;and&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iufrancia\/\" target=\"_blank\">Montpellier<\/a>, en Francia; y en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iuBuenosAires\/\" target=\"_blank\">Buenos Aires<\/a>, Argentina. Adem\u00e1s, la federaci\u00f3n dispone de la asamblea&nbsp;<a href=\"http:\/\/iuexterior.org\/en\/2020\/01\/31\/nace-iu-global-una-asamblea-virtual-para-permitir-la-participacion-de-la-militancia-sin-asamblea-local-cercana\/\">IU Global<\/a>, por medio de la cual participa la militancia dispersa por el mundo sin acceso a una asamblea local propia.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Descendiente de familia espa\u00f1ola y militante de Izquierda Unida en Buenos Aires, Moura ha mantenido reuniones con diputados de Unidas Podemos en el Congreso y con la oficina local de &hellip;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>","protected":false},"author":3,"featured_media":1531,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,1,25,8,32,29,112],"tags":[],"class_list":["post-1516","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-acciones","category-actualidad","category-asambleas","category-destacado","category-federacion","category-iu-buenos-aires","category-ley-de-descendientes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/iuexterior.org\/en\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\" \/>\n<meta property=\"og:description\" content=\"Descendiente de familia espa\u00f1ola y militante de Izquierda Unida en Buenos Aires, Moura ha mantenido reuniones con diputados de Unidas Podemos en el Congreso y con la oficina local de &hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/iuexterior.org\/en\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-10T07:29:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-30T09:04:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alicia Gab\u00e1n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alicia Gab\u00e1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/\",\"url\":\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/\",\"name\":\"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\",\"isPartOf\":{\"@id\":\"http:\/\/iuexterior.org\/gl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg\",\"datePublished\":\"2020-02-10T07:29:02+00:00\",\"dateModified\":\"2020-04-30T09:04:35+00:00\",\"author\":{\"@id\":\"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0cc306dc9015c21185f0e0684d92e410\"},\"breadcrumb\":{\"@id\":\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#primaryimage\",\"url\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg\",\"contentUrl\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/iuexterior.org\/gl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/iuexterior.org\/gl\/#website\",\"url\":\"http:\/\/iuexterior.org\/gl\/\",\"name\":\"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\",\"description\":\"La federaci\u00f3n de IU para la ciudadan\u00eda espa\u00f1ola emigrada.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/iuexterior.org\/gl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0cc306dc9015c21185f0e0684d92e410\",\"name\":\"Alicia Gab\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df0b72f6e92404b4e1f3b74c185179a121a04b2aa101c4b564859d290506f307?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df0b72f6e92404b4e1f3b74c185179a121a04b2aa101c4b564859d290506f307?s=96&d=mm&r=g\",\"caption\":\"Alicia Gab\u00e1n\"},\"url\":\"http:\/\/iuexterior.org\/en\/author\/aliciagaban\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/iuexterior.org\/en\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/","og_locale":"en_GB","og_type":"article","og_title":"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","og_description":"Descendiente de familia espa\u00f1ola y militante de Izquierda Unida en Buenos Aires, Moura ha mantenido reuniones con diputados de Unidas Podemos en el Congreso y con la oficina local de &hellip;","og_url":"http:\/\/iuexterior.org\/en\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/","og_site_name":"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","article_published_time":"2020-02-10T07:29:02+00:00","article_modified_time":"2020-04-30T09:04:35+00:00","og_image":[{"width":1600,"height":900,"url":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg","type":"image\/jpeg"}],"author":"Alicia Gab\u00e1n","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alicia Gab\u00e1n","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/","url":"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/","name":"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","isPartOf":{"@id":"http:\/\/iuexterior.org\/gl\/#website"},"primaryImageOfPage":{"@id":"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#primaryimage"},"image":{"@id":"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#primaryimage"},"thumbnailUrl":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg","datePublished":"2020-02-10T07:29:02+00:00","dateModified":"2020-04-30T09:04:35+00:00","author":{"@id":"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0cc306dc9015c21185f0e0684d92e410"},"breadcrumb":{"@id":"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#primaryimage","url":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg","contentUrl":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/Reuniones-Pilu.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"http:\/\/iuexterior.org\/eu\/2020\/02\/10\/la-corresponsable-de-iu-exterior-pilar-moura-cierra-una-semana-de-encuentros-con-agentes-politicos-y-sociales-en-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/iuexterior.org\/gl\/"},{"@type":"ListItem","position":2,"name":"La corresponsable de Acci\u00f3n Pol\u00edtica de IU Exterior Pilar Moura cierra una semana de encuentros con agentes pol\u00edticos y sociales en Madrid"}]},{"@type":"WebSite","@id":"http:\/\/iuexterior.org\/gl\/#website","url":"http:\/\/iuexterior.org\/gl\/","name":"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","description":"La federaci\u00f3n de IU para la ciudadan\u00eda espa\u00f1ola emigrada.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/iuexterior.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0cc306dc9015c21185f0e0684d92e410","name":"Alicia Gab\u00e1n","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/df0b72f6e92404b4e1f3b74c185179a121a04b2aa101c4b564859d290506f307?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df0b72f6e92404b4e1f3b74c185179a121a04b2aa101c4b564859d290506f307?s=96&d=mm&r=g","caption":"Alicia Gab\u00e1n"},"url":"http:\/\/iuexterior.org\/en\/author\/aliciagaban\/"}]}},"_links":{"self":[{"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/posts\/1516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/comments?post=1516"}],"version-history":[{"count":0,"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/posts\/1516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/media\/1531"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/media?parent=1516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/categories?post=1516"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/en\/wp-json\/wp\/v2\/tags?post=1516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}