{"id":1488,"date":"2020-02-04T11:00:00","date_gmt":"2020-02-04T10:00:00","guid":{"rendered":"http:\/\/iuexterior.org\/?p=1488"},"modified":"2021-01-19T21:58:44","modified_gmt":"2021-01-19T20:58:44","slug":"eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/de\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/","title":{"rendered":"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb"},"content":{"rendered":"<p class=\"has-medium-font-size\">La asamblea de IU Bruselas publica el v\u00eddeo completo del evento &#8216;Precariedad laboral y emigraci\u00f3n: El caso de #HolandaETT&#8217;, organizado conjuntamente con el c\u00edrculo Podemos B\u00e9lgica.<\/p>\n\n\n\n<p><strong>Eduardo Vel\u00e1zquez, <\/strong>coportavoz de la federaci\u00f3n de <strong>Izquierda Unida en el Exterior (IU Exterior)<\/strong>; <strong>Alicia Gab\u00e1n<\/strong>, coordinadora de <strong>IU Br\u00fcssel <\/strong>y <strong>corresponsable de Comunicaci\u00f3n<\/strong> de la federaci\u00f3n; y <strong>Javier Polanco, miembro de Podemos B\u00e9lgica<\/strong>, ofrecieron el pasado s\u00e1bado, 1 de febrero, la charla <em><a aria-label=\" (se abre en una nueva pesta\u00f1a)\" rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/events\/254712735513971\/\" target=\"_blank\">Precariedad laboral y emigraci\u00f3n: El caso de las ETT en Pa\u00edses Bajos<\/a><\/em>, organizada por<strong> IU Br\u00fcssel<\/strong> y el <strong>C\u00edrculo Podemos B\u00e9lgica<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Acto &quot;Precariedad laboral y emigraci\u00f3n: el caso de las ETTs en Pa\u00edses Bajos&quot;\" width=\"618\" height=\"348\" src=\"https:\/\/www.youtube.com\/embed\/DBrjAbncx0U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Puedes ver el v\u00eddeo en <a href=\"https:\/\/www.facebook.com\/IUBruselas\/posts\/10156818714752026\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"nuestro perfil de Facebook (se abre en una nueva pesta\u00f1a)\">nuestro perfil de Facebook<\/a> o en el <a rel=\"noreferrer noopener\" aria-label=\"Youtube de IU Exterior (se abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.youtube.com\/watch?v=DBrjAbncx0U\" target=\"_blank\">Youtube de IU Exterior<\/a><\/h4>\n\n\n\n<p><em>\u00abSer doctor no te salva de esto\u00bb<\/em>, declar\u00f3 en el encuentro <strong>Vel\u00e1zquez<\/strong>. <em>\u00abCualquiera puede acabar en una situaci\u00f3n as\u00ed\u00bb<\/em>. Tras entrevistarse sobre el terreno con trabajadoras y trabajadores afectados <a rel=\"noreferrer noopener\" href=\"http:\/\/iuexterior.org\/de\/2019\/03\/28\/una-delegacion-de-iu-exterior-visita-holanda-para-conocer-los-problemas-de-la-emigracion-espanola-en-las-ett\/\" target=\"_blank\">hace un a\u00f1o<\/a>, <strong>IU Exterior<\/strong> <a href=\"http:\/\/iuexterior.org\/de\/2019\/04\/05\/iu-exterior-denunciara-ante-el-parlamento-europeo-la-situacion-de-los-y-las-trabajadoras-de-las-ett-en-holanda\/\">decidi\u00f3 denunciar ante la Comisi\u00f3n de Peticiones del Parlamento Europeo<\/a>   una situaci\u00f3n que podr\u00eda afectar a entre 3.000 y 5.000 personas de origen espa\u00f1ol en Holanda, a las que se suman de otras nacionalidades.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FIUExterior%2Fposts%2F585459422017929&amp;width=500\" width=\"500\" height=\"732\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\n\n\n\n<h4 class=\"wp-block-heading\">IU Exterior llama a sumarse con adhesiones<\/h4>\n\n\n\n<p>La federaci\u00f3n de <strong>Izquierda Unida en el Exterior (IU Exterior)<\/strong> <a rel=\"noreferrer noopener\" aria-label=\"viene llamando a la ciudadan\u00eda de dentro y fuera del Estado espa\u00f1ol (se abre en una nueva pesta\u00f1a)\" href=\"http:\/\/iuexterior.org\/de\/2019\/10\/29\/iu-exterior-pide-adhesiones-a-su-peticion-al-parlamento-y-a-la-comision-europea-para-poner-fin-a-la-explotacion-laboral-de-las-ett-en-holanda\/\" target=\"_blank\">viene llamando a la ciudadan\u00eda de dentro y fuera del Estado espa\u00f1ol<\/a> a mostrar su adhesi\u00f3n a la <a rel=\"noreferrer noopener\" href=\"https:\/\/petiport.secure.europarl.europa.eu\/petitions\/es\/petition\/content\/0335%252F2019\/html\/Petici%25C3%25B3n-n.%25C2%25BA%25C2%25A00335%252F2019%252C-presentada-por-Eduardo-Vel%25C3%25A1zquez%252C-de-nacionalidad-espa%25C3%25B1ola%252C-en-nombre-de-IU-Exterior%252C-sobre-la-situaci%25C3%25B3n-de-las-personas-trabajadoras-migrantes-dentro-de-la-UE-contratadas-por-empresas-de-trabajo-temporal-en-los-Pa%25C3%25ADses-Bajos\" target=\"_blank\">petici\u00f3n  0335\/2019 sobre la situaci\u00f3n de las personas trabajadoras migrantes  dentro de la UE contratadas por empresas de trabajo temporal en los  Pa\u00edses Bajos<\/a>, presentada por su coportavoz <strong>Eduardo Vel\u00e1zquez<\/strong> y admitida a tr\u00e1mite por el <strong>Parlamento Europeo<\/strong>.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">&#x1f1f3;&#x1f1f1; Una delegaci\u00f3n de <a href=\"https:\/\/twitter.com\/IUExterior?ref_src=twsrc%5Etfw\">@IUExterior<\/a> visit\u00f3 el pasado fin de semana el sur de <a href=\"https:\/\/twitter.com\/hashtag\/Pa%C3%ADsesBajos?src=hash&amp;ref_src=twsrc%5Etfw\">#Pa\u00edsesBajos<\/a> para conocer los problemas de la <a href=\"https:\/\/twitter.com\/hashtag\/emigraci%C3%B3n?src=hash&amp;ref_src=twsrc%5Etfw\">#emigraci\u00f3n<\/a> espa\u00f1ola que ha llegado a este pa\u00eds para trabajar en <a href=\"https:\/\/twitter.com\/hashtag\/HolandaETT?src=hash&amp;ref_src=twsrc%5Etfw\">#HolandaETT<\/a>. <br><br>&#x1f4f9; V\u00eddeo completo &#x1f449; <a href=\"https:\/\/t.co\/ox4prTA7xJ\">https:\/\/t.co\/ox4prTA7xJ<\/a><\/p>\u2014 IU Exterior&#x1f53b; (@IUExterior) <a href=\"https:\/\/twitter.com\/IUExterior\/status\/1114105397588238336?ref_src=twsrc%5Etfw\">April 5, 2019<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>En ella, <strong>IU Exterior<\/strong> solicita al <strong>Parlamento Europeo <\/strong>y a la <strong>Comisi\u00f3n Europea <\/strong>que act\u00faen para poner fin a esta situaci\u00f3n de explotaci\u00f3n y <em>\u00aba la posible violaci\u00f3n del Derecho de la UE y de los derechos recogidos en la Carta de Derechos Fundamentales de la Uni\u00f3n\u00bb. <\/em><\/p>\n\n\n\n<p><em>\u00abEstos trabajadores, en muchas ocasiones, son reclutados a trav\u00e9s  de promesas falsas e informaci\u00f3n incompleta sobre las condiciones de trabajo, firmando precontratos en Espa\u00f1a que nada tienen que ver con los contratos definitivos que firman una vez se han trasladado a los Pa\u00edses  Bajos\u00bb<\/em>, detalla la petici\u00f3n. <\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">&#x1f3a5; \u00bfSabes c\u00f3mo viven muchas personas emigradas en <a href=\"https:\/\/twitter.com\/hashtag\/HolandaETT?src=hash&amp;ref_src=twsrc%5Etfw\">#HolandaETT<\/a>? Un informe de <a href=\"https:\/\/twitter.com\/fundacion1mayo?ref_src=twsrc%5Etfw\">@fundacion1mayo<\/a> de <a href=\"https:\/\/twitter.com\/CCOO?ref_src=twsrc%5Etfw\">@ccoo<\/a> recoge numerosos casos de <a href=\"https:\/\/twitter.com\/hashtag\/Explotacion?src=hash&amp;ref_src=twsrc%5Etfw\">#Explotacion<\/a> laboral.<br><br>\u00a1Dentro v\u00eddeo! &#x1f447; <a href=\"https:\/\/t.co\/nhcmfuLs2W\">pic.twitter.com\/nhcmfuLs2W<\/a><\/p>\u2014 IU Exterior&#x1f53b; (@IUExterior) <a href=\"https:\/\/twitter.com\/IUExterior\/status\/956102696846680064?ref_src=twsrc%5Etfw\">January 24, 2018<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>A iniciativa de&nbsp;<strong>IU Exterior<\/strong>, el hoy exdiputado de&nbsp;<strong>IU Miguel \u00c1ngel Bustamante<\/strong>&nbsp;pregunt\u00f3 al Ejecutivo de Rajoy sobre esta problem\u00e1tica&nbsp;<a href=\"http:\/\/iuexterior.org\/de\/2018\/01\/24\/iu-exterior-denuncia-en-el-congreso-la-explotacion-de-trabajadoras-y-trabajadores-espanoles-en-holanda\/\">a comienzos de 2018 en sesi\u00f3n parlamentaria<\/a>. Posteriormente,&nbsp;<a href=\"http:\/\/iuexterior.org\/de\/2018\/03\/17\/el-gobierno-reconoce-a-iu-abusos-de-las-ett-con-trabajadores-espanoles-en-holanda-pero-no-ofrece-soluciones\/\">el Gobierno del PP reconoci\u00f3 por escrito los abusos e irregularidades<\/a>&nbsp;a las que se enfrentan los y las trabajadoras desplazadas en el  extranjero. Sin embargo, desde Moncloa se mostraron satisfechos con la respuesta que se da a los afectados y no ofrecieron alternativa alguna  para erradicar los problemas identificados. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo sumarse a la petici\u00f3n<\/h4>\n\n\n\n<p>La federaci\u00f3n indica que, para sumarse a la petici\u00f3n, solo es necesario <a href=\"https:\/\/petiport.secure.europarl.europa.eu\/petitions\/es\/registration\/register#frm\">registrarse con nuestros datos personales en el portal de Peticiones del Parlamento Europeo<\/a> y luego hacer clic en el bot\u00f3n de adhesi\u00f3n situado en la parte inferior de <a rel=\"noreferrer noopener\" href=\"https:\/\/petiport.secure.europarl.europa.eu\/petitions\/es\/petition\/content\/0335%252F2019\/html\/Petici%25C3%25B3n-n.%25C2%25BA%25C2%25A00335%252F2019%252C-presentada-por-Eduardo-Vel%25C3%25A1zquez%252C-de-nacionalidad-espa%25C3%25B1ola%252C-en-nombre-de-IU-Exterior%252C-sobre-la-situaci%25C3%25B3n-de-las-personas-trabajadoras-migrantes-dentro-de-la-UE-contratadas-por-empresas-de-trabajo-temporal-en-los-Pa%25C3%25ADses-Bajos\" target=\"_blank\">la p\u00e1gina de la propia petici\u00f3n<\/a>.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">&#x1f4e2; \u00a1El <a href=\"https:\/\/twitter.com\/Europarl_ES?ref_src=twsrc%5Etfw\">@Europarl_ES<\/a> ha admitido nuestra petici\u00f3n para acabar con la explotaci\u00f3n de las empresas de trabajo temporal en Holanda!<br><br>&#x270d;&#xfe0f; Para sumarte tan solo tienes que:<br>1&#xfe0f;&#x20e3; Registrarte: <a href=\"https:\/\/t.co\/5LhmPlYNj7\">https:\/\/t.co\/5LhmPlYNj7<\/a><br>2&#xfe0f;&#x20e3; Adherirte: <a href=\"https:\/\/t.co\/KGpXtIjiRo\">https:\/\/t.co\/KGpXtIjiRo<\/a><a href=\"https:\/\/twitter.com\/hashtag\/HolandaETT?src=hash&amp;ref_src=twsrc%5Etfw\">#HolandaETT<\/a><a href=\"https:\/\/t.co\/yNVEov9lnR\">https:\/\/t.co\/yNVEov9lnR<\/a><\/p>\u2014 IU Exterior&#x1f53b; (@IUExterior) <a href=\"https:\/\/twitter.com\/IUExterior\/status\/1189085384799588352?ref_src=twsrc%5Etfw\">October 29, 2019<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>Desde <strong>IU Exterior<\/strong> invitan adem\u00e1s a compartir esta  iniciativa en redes sociales con el hashtag <a href=\"https:\/\/twitter.com\/search?q=%23HolandaETT&amp;src=typed_query&amp;f=live\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"#HolandaETT (se abre en una nueva pesta\u00f1a)\"><em>#HolandaETT<\/em><\/a> para animar a  m\u00e1s gente a sumarse a la petici\u00f3n y as\u00ed aumentar la presi\u00f3n para acabar  con esta lacra.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcber die IU Exterior<\/h2>\n\n\n\n<p>La&nbsp;<strong>Federaci\u00f3n del Exterior de Izquierda Unida&nbsp;<\/strong><a href=\"http:\/\/iuexterior.org\/de\/2017\/04\/30\/la-federacion-del-exterior-de-iu-nace-para-movilizar-politicamente-a-la-emigracion-espanola\/\">naci\u00f3 en abril de 2017<\/a>&nbsp;para movilizar pol\u00edticamente a la emigraci\u00f3n espa\u00f1ola y darle voz a sus reivindicaciones. Actualmente contamos con asambleas estables en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUBruselas\/\" target=\"_blank\">Bruselas<\/a>, B\u00e9lgica;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iuberlin\/\" target=\"_blank\">Berl\u00edn<\/a>&nbsp;y&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iufrankfurt\/\" target=\"_blank\">Frankfurt<\/a>, en Alemania;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IzquierdaUnidaLuxemburgo\/\" target=\"_blank\">Luxemburgo<\/a>;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUZurich\/\" target=\"_blank\">Z\u00farich<\/a>, en Suiza; en&nbsp;<a href=\"https:\/\/www.facebook.com\/izquierdaunidalyon\/\">Lyon<\/a>,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUToulouse\/\" target=\"_blank\">Toulouse<\/a>&nbsp;y&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iufrancia\/\" target=\"_blank\">Montpellier<\/a>, en Francia; y en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iuBuenosAires\/\" target=\"_blank\">Buenos Aires<\/a>, Argentina. Adem\u00e1s, la federaci\u00f3n dispone de la asamblea&nbsp;<a href=\"http:\/\/iuexterior.org\/de\/2020\/01\/31\/nace-iu-global-una-asamblea-virtual-para-permitir-la-participacion-de-la-militancia-sin-asamblea-local-cercana\/\">IU Global<\/a>, por medio de la cual participa la militancia dispersa por el mundo sin acceso a una asamblea local propia.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La asamblea de IU Bruselas publica el v\u00eddeo completo del evento &#8216;Precariedad laboral y emigraci\u00f3n: El caso de #HolandaETT&#8217;, organizado conjuntamente con el c\u00edrculo Podemos B\u00e9lgica. Eduardo Vel\u00e1zquez, coportavoz de &hellip;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>","protected":false},"author":2,"featured_media":1492,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,1,25,8,32,28,115,9],"tags":[],"class_list":["post-1488","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-acciones","category-actualidad","category-asambleas","category-destacado","category-federacion","category-iu-bruselas","category-trabajadoras-desplazadas","category-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iuexterior.org\/de\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\" \/>\n<meta property=\"og:description\" content=\"La asamblea de IU Bruselas publica el v\u00eddeo completo del evento &#8216;Precariedad laboral y emigraci\u00f3n: El caso de #HolandaETT&#8217;, organizado conjuntamente con el c\u00edrculo Podemos B\u00e9lgica. Eduardo Vel\u00e1zquez, coportavoz de &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iuexterior.org\/de\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/\" \/>\n<meta property=\"og:site_name\" content=\"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-04T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-19T20:58:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Blanco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Blanco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/\",\"url\":\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/\",\"name\":\"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\",\"isPartOf\":{\"@id\":\"https:\/\/iuexterior.org\/gl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg\",\"datePublished\":\"2020-02-04T10:00:00+00:00\",\"dateModified\":\"2021-01-19T20:58:44+00:00\",\"author\":{\"@id\":\"https:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774\"},\"breadcrumb\":{\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#primaryimage\",\"url\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg\",\"contentUrl\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"De izquierda a derecha, Javier Polanco, miembro de Podemos B\u00e9lgica; Alicia Gab\u00e1n, coordinadora de IU Bruselas y corresponsable de Comunicaci\u00f3n de IU Exterior; y Eduardo Vel\u00e1zquez, coportavoz de la federaci\u00f3n.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/iuexterior.org\/gl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/iuexterior.org\/gl\/#website\",\"url\":\"https:\/\/iuexterior.org\/gl\/\",\"name\":\"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\",\"description\":\"La federaci\u00f3n de IU para la ciudadan\u00eda espa\u00f1ola emigrada.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/iuexterior.org\/gl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774\",\"name\":\"Juan Blanco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/iuexterior.org\/gl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g\",\"caption\":\"Juan Blanco\"},\"url\":\"http:\/\/iuexterior.org\/de\/author\/juanblanco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iuexterior.org\/de\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/","og_locale":"de_DE","og_type":"article","og_title":"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","og_description":"La asamblea de IU Bruselas publica el v\u00eddeo completo del evento &#8216;Precariedad laboral y emigraci\u00f3n: El caso de #HolandaETT&#8217;, organizado conjuntamente con el c\u00edrculo Podemos B\u00e9lgica. Eduardo Vel\u00e1zquez, coportavoz de &hellip;","og_url":"https:\/\/iuexterior.org\/de\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/","og_site_name":"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","article_published_time":"2020-02-04T10:00:00+00:00","article_modified_time":"2021-01-19T20:58:44+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg","type":"image\/jpeg"}],"author":"Juan Blanco","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Juan Blanco","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/","url":"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/","name":"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","isPartOf":{"@id":"https:\/\/iuexterior.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#primaryimage"},"image":{"@id":"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#primaryimage"},"thumbnailUrl":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg","datePublished":"2020-02-04T10:00:00+00:00","dateModified":"2021-01-19T20:58:44+00:00","author":{"@id":"https:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774"},"breadcrumb":{"@id":"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#primaryimage","url":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg","contentUrl":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/02\/IMG_9619-scaled.jpg","width":2560,"height":1440,"caption":"De izquierda a derecha, Javier Polanco, miembro de Podemos B\u00e9lgica; Alicia Gab\u00e1n, coordinadora de IU Bruselas y corresponsable de Comunicaci\u00f3n de IU Exterior; y Eduardo Vel\u00e1zquez, coportavoz de la federaci\u00f3n."},{"@type":"BreadcrumbList","@id":"https:\/\/iuexterior.org\/ca\/2020\/02\/04\/eduardo-velazquez-coportavoz-de-iu-exterior-sobre-la-precariedad-en-las-ett-de-holanda-ser-doctor-no-te-salva-de-esto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iuexterior.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Eduardo Vel\u00e1zquez, coportavoz de IU Exterior, sobre la precariedad en las ETT de Holanda: \u00abSer doctor no te salva de esto\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/iuexterior.org\/gl\/#website","url":"https:\/\/iuexterior.org\/gl\/","name":"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","description":"La federaci\u00f3n de IU para la ciudadan\u00eda espa\u00f1ola emigrada.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iuexterior.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774","name":"Juan Blanco","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/iuexterior.org\/gl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g","caption":"Juan Blanco"},"url":"http:\/\/iuexterior.org\/de\/author\/juanblanco\/"}]}},"_links":{"self":[{"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/posts\/1488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/comments?post=1488"}],"version-history":[{"count":0,"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/posts\/1488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/media\/1492"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/media?parent=1488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/categories?post=1488"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/de\/wp-json\/wp\/v2\/tags?post=1488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}