{"id":1923,"date":"2020-06-09T09:00:00","date_gmt":"2020-06-09T07:00:00","guid":{"rendered":"http:\/\/iuexterior.org\/?p=1923"},"modified":"2020-06-08T18:15:37","modified_gmt":"2020-06-08T16:15:37","slug":"iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/","title":{"rendered":"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania"},"content":{"rendered":"<p class=\"has-medium-font-size\">La asamblea de IU Exterior en Berl\u00edn considera que la arquitectura europea provocar\u00e1 una emigraci\u00f3n desde el sur terciarizado a la Europa industrial.<\/p>\n\n\n\n<p>La asamblea de <strong>Izquierda Unida Berl\u00edn (IU Berl\u00edn) <\/strong>ha evaluado en su \u00faltima reuni\u00f3n el impacto de la crisis sanitaria y su derivada econ\u00f3mica en el movimiento de poblaci\u00f3n hacia <strong>Alemania<\/strong>. Consideran que con toda probabilidad volver\u00e1 a producirse una oleada migratoria desde Espa\u00f1a, cuyo modelo econ\u00f3mico construido durante las \u00faltimas d\u00e9cadas se basa en el sol y el ladrillo, hacia la Europa m\u00e1s industrializada y, concretamente, Alemania. Como denunci\u00f3 el <strong>ministro de Consumo, Alberto Garz\u00f3n<\/strong>, el sector tur\u00edstico es estacional y est\u00e1 extremadamente precarizado. Si a ello se le suma la crisis sanitaria y la ca\u00edda del flujo tur\u00edstico, esta asamblea de la federaci\u00f3n de <strong>Izquierda Unida a l'Exterior (IU Exterior)<\/strong> en <strong>Berl\u00edn<\/strong> considera que es m\u00e1s que probable este movimiento migratorio.<\/p>\n\n\n\n<p><strong>Jaime Mart\u00ednez, responsable de Comunicaci\u00f3n y Redes <\/strong>de la asamblea advierte de que <em>\u00abse nota en las \u00faltimas semanas en los grupos de Facebook de espa\u00f1oles emigrantes en Berl\u00edn un creciente n\u00famero de consultas sobre c\u00f3mo emigrar a la capital alemana, sobre la situaci\u00f3n laboral presente o c\u00f3mo encontrar una vivienda\u00bb<\/em>. Esto, eval\u00faa, <em>\u00abes un s\u00edntoma de un inminente flujo de personas hacia Alemania<\/em>\u00bb.<\/p>\n\n\n\n<p><strong>Norma Lorenzo, coordinadora de la asamblea<\/strong>, cree que <em>\u00abhay que prepararse desde ya para hacer frente desde el punto de vista pol\u00edtico y social a esta realidad inminente\u00bb<\/em>. Por eso, considera que <em>\u00abes fundamental apoyarse como comunidad y organizarse para defender los derechos de la emigraci\u00f3n y evitar posibles abusos, como ha sucedido en ocasiones anteriores\u00bb<\/em>.<\/p>\n\n\n\n<p>Desde la asamblea tambi\u00e9n recuerdan que el flujo migratorio de poblaci\u00f3n espa\u00f1ola a <strong>Berl\u00edn <\/strong>no ha parado desde el inicio de la anterior crisis econ\u00f3mica. <strong>Luis Sanz, responsable de Acci\u00f3n Pol\u00edtica<\/strong>, constata que <em>\u00abaunque en los \u00faltimos a\u00f1os el n\u00famero de espa\u00f1oles residentes en Alemania no ha aumentado al ritmo de los a\u00f1os 2011-2015, en los que crec\u00eda a raz\u00f3n de m\u00e1s de 10.000 personas por a\u00f1o, la migraci\u00f3n espa\u00f1ola no ha dejado de aumentar. Se trata de una poblaci\u00f3n muy heterog\u00e9nea, pero destacan los migrantes j\u00f3venes, siendo los grupos de edad m\u00e1s numerosos los de edades comprendidas entre 25 y 35 y entre 35 y 45 a\u00f1os\u00bb.<\/em><\/p>\n\n\n\n<p>Con todo ello, la organizaci\u00f3n de <strong>IU <\/strong>en la capital alemana se ofrece como herramienta de organizaci\u00f3n y lucha por los derechos de la comunidad espa\u00f1ola emigrada en <strong>Berl\u00edn <\/strong>y <strong>Alemania<\/strong>, y recuerdan que la federaci\u00f3n de <strong>IU Exterior <\/strong>tambi\u00e9n tiene presencia con asambleas de base en distintas ciudades de <strong>Francia<\/strong>, <strong>Suiza<\/strong>, <strong>Luxemburgo<\/strong>, <strong>B\u00e9lgica <\/strong>y <strong>Argentina<\/strong>, as\u00ed como la asamblea virtual <strong>IU Global<\/strong>, para aquellas personas sin asamblea de referencia cerca de su lugar de residencia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sobre IU Exterior<\/h2>\n\n\n\n<p class=\"translation-block\">La Federaci\u00f3 de l'Exterior d'Esquerra Unida va n\u00e9ixer a l'abril de 2017 per a mobilitzar pol\u00edticament a l'emigraci\u00f3 espanyola i donar-li veu a les seves reivindicacions. Actualment comptem amb assemblees estables a Brussel\u00b7les, B\u00e8lgica; Berl\u00edn i Frankfurt, a Alemanya; Luxemburg; Zuric, a Su\u00efssa; a Li\u00f3 i Tolosa, a Fran\u00e7a; i a Buenos Aires, l'Argentina. A m\u00e9s, la federaci\u00f3 disposa de l'assemblea IU Global, per mitj\u00e0 de la qual participa la milit\u00e0ncia dispersa pel m\u00f3n sense acc\u00e9s a una assemblea local pr\u00f2pia.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La asamblea de IU Exterior en Berl\u00edn considera que la arquitectura europea provocar\u00e1 una emigraci\u00f3n desde el sur terciarizado a la Europa industrial. La asamblea de Izquierda Unida Berl\u00edn (IU &hellip;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>","protected":false},"author":2,"featured_media":1924,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,1,8,27,115],"tags":[],"class_list":["post-1923","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-acciones","category-actualidad","category-destacado","category-iu-berlin","category-trabajadoras-desplazadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\" \/>\n<meta property=\"og:description\" content=\"La asamblea de IU Exterior en Berl\u00edn considera que la arquitectura europea provocar\u00e1 una emigraci\u00f3n desde el sur terciarizado a la Europa industrial. La asamblea de Izquierda Unida Berl\u00edn (IU &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/\" \/>\n<meta property=\"og:site_name\" content=\"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-09T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Blanco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Blanco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/\",\"url\":\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/\",\"name\":\"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\",\"isPartOf\":{\"@id\":\"http:\/\/iuexterior.org\/gl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg\",\"datePublished\":\"2020-06-09T07:00:00+00:00\",\"author\":{\"@id\":\"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774\"},\"breadcrumb\":{\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#primaryimage\",\"url\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg\",\"contentUrl\":\"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/iuexterior.org\/gl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/iuexterior.org\/gl\/#website\",\"url\":\"http:\/\/iuexterior.org\/gl\/\",\"name\":\"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)\",\"description\":\"La federaci\u00f3n de IU para la ciudadan\u00eda espa\u00f1ola emigrada.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/iuexterior.org\/gl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774\",\"name\":\"Juan Blanco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g\",\"caption\":\"Juan Blanco\"},\"url\":\"http:\/\/iuexterior.org\/ca\/author\/juanblanco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/","og_locale":"ca_ES","og_type":"article","og_title":"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","og_description":"La asamblea de IU Exterior en Berl\u00edn considera que la arquitectura europea provocar\u00e1 una emigraci\u00f3n desde el sur terciarizado a la Europa industrial. La asamblea de Izquierda Unida Berl\u00edn (IU &hellip;","og_url":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/","og_site_name":"Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","article_published_time":"2020-06-09T07:00:00+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg","type":"image\/jpeg"}],"author":"Juan Blanco","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Juan Blanco","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/","url":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/","name":"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania - Federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)","isPartOf":{"@id":"http:\/\/iuexterior.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#primaryimage"},"image":{"@id":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#primaryimage"},"thumbnailUrl":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg","datePublished":"2020-06-09T07:00:00+00:00","author":{"@id":"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774"},"breadcrumb":{"@id":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#primaryimage","url":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg","contentUrl":"http:\/\/iuexterior.org\/wp-content\/uploads\/2020\/06\/photo_2020-06-08_18-06-12.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/iuexterior.org\/ca\/2020\/06\/09\/iu-berlin-alerta-de-una-probable-nueva-oleada-migratoria-de-espana-a-alemania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/iuexterior.org\/gl\/"},{"@type":"ListItem","position":2,"name":"IU Berl\u00edn alerta de una probable nueva oleada migratoria de Espa\u00f1a a Alemania"}]},{"@type":"WebSite","@id":"http:\/\/iuexterior.org\/gl\/#website","url":"http:\/\/iuexterior.org\/gl\/","name":"Federaci\u00f3 Izquierda Unida a l'Exterior (IU Exterior)","description":"La federaci\u00f3n de IU para la ciudadan\u00eda espa\u00f1ola emigrada.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/iuexterior.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/0987e941f747f6257ffff87c8f1d1774","name":"Juan Blanco","image":{"@type":"ImageObject","inLanguage":"ca","@id":"http:\/\/iuexterior.org\/gl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c34f14293a64c2be8830f7330dca63726c12e271d86e38ed3f6aac418aae4427?s=96&d=mm&r=g","caption":"Juan Blanco"},"url":"http:\/\/iuexterior.org\/ca\/author\/juanblanco\/"}]}},"_links":{"self":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/1923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/comments?post=1923"}],"version-history":[{"count":0,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/1923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/media\/1924"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/media?parent=1923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/categories?post=1923"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/tags?post=1923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}