{"id":1398,"date":"2019-12-31T12:50:46","date_gmt":"2019-12-31T11:50:46","guid":{"rendered":"http:\/\/iuexterior.org\/?p=1398"},"modified":"2020-04-30T10:49:26","modified_gmt":"2020-04-30T08:49:26","slug":"iu-exterior-saluda-la-inclusion-de-demandas-de-la-emigracion-espanola-en-el-acuerdo-con-el-psoe","status":"publish","type":"post","link":"http:\/\/iuexterior.org\/ca\/2019\/12\/31\/iu-exterior-saluda-la-inclusion-de-demandas-de-la-emigracion-espanola-en-el-acuerdo-con-el-psoe\/","title":{"rendered":"IU Exterior saluda la inclusi\u00f3n de demandas de la emigraci\u00f3n espa\u00f1ola en el acuerdo con el PSOE"},"content":{"rendered":"<p class=\"has-medium-font-size wp-block-paragraph\">La derogaci\u00f3n del voto rogado, la aprobaci\u00f3n de la ley de nacionalidad para descendientes o un plan de retorno para emigrantes son algunas de las medidas incluidas en el pacto para un Gobierno de progreso anunciado ayer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00abSon demandas hist\u00f3ricas de la emigraci\u00f3n espa\u00f1ola, y con este gobierno progresista tenemos una oportunidad \u00fanica para llevarlas a cabo\u00bb<\/em>, ha declarado <strong>Eduardo Vel\u00e1zquez, coportavoz de la federaci\u00f3n de Izquierda Unida en el Exterior (IU Exterior)<\/strong>. <em>\u00abDesde IU Exterior velaremos porque estas medidas incluidas en el acuerdo de Gobierno con el PSOE se cumplan\u00bb.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/velazquedu\/status\/1211944323169828865\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/izquierdaunida.org\/2019\/12\/30\/documento-coalicion-progresista-un-nuevo-acuerdo-para-espana\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Consulta el documento completo (se abre en una nueva pesta\u00f1a)\">Consulta el documento completo<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab<strong>Eliminaremos el voto rogado<\/strong> en las elecciones auton\u00f3micas, generales, y europeas y municipales\u00bb<\/em>, <a href=\"https:\/\/izquierdaunida.org\/2019\/12\/30\/documento-coalicion-progresista-un-nuevo-acuerdo-para-espana\/\">se\u00f1ala el acuerdo<\/a> en su punto 5.7. Se trata de una de las demandas m\u00e1s recurrentes por parte de la federaci\u00f3n de IU Exterior, que incluso prepara una <a href=\"http:\/\/iuexterior.org\/ca\/2019\/12\/12\/iu-exterior-recopila-casos-de-incidencias-con-el-voto-rogado-para-preparar-una-denuncia-colectiva\/\">demanda colectiva ante el Defensor del Pueblo en ese sentido<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra de las medidas m\u00e1s bienvenidas es la creaci\u00f3n de <em>\u00ab<strong>Programas de Retorno de personas emigradas<\/strong> para recuperar a quienes salieron de nuestro pa\u00eds en busca de un empleo y que son tan necesarios para nuestra econom\u00eda\u00bb<\/em> (<a href=\"https:\/\/izquierdaunida.org\/2019\/12\/30\/documento-coalicion-progresista-un-nuevo-acuerdo-para-espana\/\">punto 1.12<\/a>). Esta problem\u00e1tica fue incluso abordada en el documento <em>Retorno: perspectivas desde la emigraci\u00f3n<\/em>, emanado de unas <a href=\"http:\/\/iuexterior.org\/ca\/2018\/06\/01\/iu-exterior-reune-a-la-emigracion-espanola-en-el-parlamento-europeo-para-recoger-propuestas-porunretornodigno\/\">jornadas de trabajo organizadas por IU Exterior en el Parlamento Europeo<\/a>, que acab\u00f3 reflejado en <a href=\"http:\/\/iuexterior.org\/ca\/2019\/04\/08\/ayuntamientos-con-representacion-de-iu-promueven-mociones-para-un-retorno-digno-de-la-emigracion\/\">numerosas mociones<\/a> y propuestas en <a href=\"http:\/\/iuexterior.org\/ca\/2019\/11\/13\/iu-cuestiona-las-politicas-de-retorno-de-la-emigracion-madrilena-en-la-asamblea-de-madrid\/\">parlamentos regionales<\/a> y ayuntamientos de todo el Estado. A ello se le suma el impulso de <em>\u00abun programa de retorno de los y las profesionales que han tenido que salir a trabajar en sistemas sanitarios fuera de Espa\u00f1a\u00bb<\/em> (<a href=\"https:\/\/izquierdaunida.org\/2019\/12\/30\/documento-coalicion-progresista-un-nuevo-acuerdo-para-espana\/\">punto 2.2.13<\/a>). <em>\u00abNo obstante, para que estas medidas se ejecuten con \u00e9xito, ser\u00e1 necesario seguir luchando por que se establezcan las condiciones laborales, econ\u00f3micas y sociales que posibiliten ese retorno de los emigrantes\u00bb<\/em>, se\u00f1ala <strong>Vel\u00e1zquez<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>reconocimiento de la nacionalidad espa\u00f1ola<\/strong> <em>\u00aba las personas descendientes de progenitores espa\u00f1oles nacidos en el extranjero en cualquier momento\u00bb<\/em> ha sido tambi\u00e9n recogida en este <a href=\"https:\/\/izquierdaunida.org\/2019\/12\/30\/documento-coalicion-progresista-un-nuevo-acuerdo-para-espana\/\">acuerdo entre Unidas Podemos y el PSOE<\/a> en su apartado 5.10. <em>\u00abEstas personas podr\u00e1n optar por la nacionalidad espa\u00f1ola en caso de que sus madres, padres, abuelas o abuelos adquirieran la nacionalidad del pa\u00eds de acogida. A esto se a\u00f1aden los casos de quienes perdieron la nacionalidad en el exilio causado por la Guerra Civil y la dictadura, a quienes se les reconocer\u00e1 con el fin de saldar esa deuda hist\u00f3rica\u00bb<\/em>. <a href=\"https:\/\/www.facebook.com\/IUExterior\/posts\/554338665130005?__xts__%5B0%5D=68.ARBEy33g6QjvugcwRdgDUn29rSdMQfEzlJednQz_ov-G23tHob5Y7YDt5l7eO-Kz7rmfTwUN7uqL4hKMU3Vt6B3J1Qk8-Dj_c4SjpXBFtGrcfZiY4f6F2CKUpjrpjOXwklXpveuIg897wMXYEuO8cKifDElNnjj5AqYOdM7dDSGsL-jQiosizsfjMM10BDke0pdMiLlES-xdx45wf113rWt5y4PJRAfXAYLkNc2TjQ8LnlXOyaeLC8L3AjFneSAjJ5xEtS8YFXj86VIu6PBLoCsuDNhyst-kfgGySk0KFq_iAo3JSgOcTdZHRYn07jjfOWn2kqFtBbOxmxIVO9CdQPE&amp;__tn__=-R\">Precisamente este mes<\/a>, la <strong>senadora de En Com\u00fa Podem Sara Vil\u00e0 <\/strong>volv\u00eda a registrar una vez m\u00e1s esta propuesta del colectivo de descendientes en el Senado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde <strong>IU Exterior<\/strong> manifiestan tambi\u00e9n su satisfacci\u00f3n por el <strong>restablecimiento de la cobertura sanitaria<\/strong>, que prev\u00e9 <em>\u00abgarantizar la recuperaci\u00f3n de la cobertura sanitaria gratuita en nuestro pa\u00eds a los ciudadanos y ciudadanas espa\u00f1oles que residen fuera de Espa\u00f1a y que no tienen derecho a la asistencia sanitaria reconocido por los pa\u00edses de acogida, o bien ese derecho no es exportable cuando se encuentren en territorio espa\u00f1ol\u00bb<\/em> (<a href=\"https:\/\/izquierdaunida.org\/2019\/12\/30\/documento-coalicion-progresista-un-nuevo-acuerdo-para-espana\/\">punto 2.2.8<\/a>).  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00abAdem\u00e1s de velar por el cumplimiento de estas medidas, que recibimos con agrado, desde <strong>IU Exterior<\/strong> seguiremos luchando por que se implementen otras como la <strong>creaci\u00f3n de una circunscripci\u00f3n exterior<\/strong> para que la emigraci\u00f3n est\u00e9 representada en los parlamentos\u00bb<\/em>, apostilla el coportavoz de <strong>IU Exterior<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-embed-facebook wp-block-embed is-type-rich is-provider-facebook\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.facebook.com\/eduardo.velazquez.771\/posts\/2774603749300494\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sobre IU Exterior<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Federaci\u00f3n del Exterior de Izquierda Unida&nbsp;<\/strong><a href=\"http:\/\/iuexterior.org\/ca\/2017\/04\/30\/la-federacion-del-exterior-de-iu-nace-para-movilizar-politicamente-a-la-emigracion-espanola\/\">naci\u00f3 en abril de 2017<\/a>&nbsp;para movilizar pol\u00edticamente a la emigraci\u00f3n espa\u00f1ola y darle voz a sus reivindicaciones. Actualmente contamos con asambleas estables en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUBruselas\/\" target=\"_blank\">Bruselas<\/a>, B\u00e9lgica;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iuberlin\/\" target=\"_blank\">Berl\u00edn<\/a>&nbsp;y&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iufrankfurt\/\" target=\"_blank\">Frankfurt<\/a>, en Alemania;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IzquierdaUnidaLuxemburgo\/\" target=\"_blank\">Luxemburgo<\/a>;&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUZurich\/\" target=\"_blank\">Z\u00farich<\/a>, en Suiza; en&nbsp;<a href=\"https:\/\/www.facebook.com\/izquierdaunidalyon\/\">Lyon<\/a>,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/IUToulouse\/\" target=\"_blank\">Toulouse<\/a>&nbsp;y&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iufrancia\/\" target=\"_blank\">Montpellier<\/a>, en Francia; y en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/iuBuenosAires\/\" target=\"_blank\">Buenos Aires<\/a>, Argentina.<\/p>","protected":false},"excerpt":{"rendered":"<p>La derogaci\u00f3n del voto rogado, la aprobaci\u00f3n de la ley de nacionalidad para descendientes o un plan de retorno para emigrantes son algunas de las medidas incluidas en el pacto &hellip;<\/p>","protected":false},"author":2,"featured_media":1400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[110,1,8,32,112,111,114],"tags":[],"class_list":["post-1398","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-acciones","category-actualidad","category-destacado","category-federacion","category-ley-de-descendientes","category-voto-rogado","category-retorno-digno"],"_links":{"self":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/1398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/comments?post=1398"}],"version-history":[{"count":7,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/1398\/revisions"}],"predecessor-version":[{"id":1408,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/posts\/1398\/revisions\/1408"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/media\/1400"}],"wp:attachment":[{"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/media?parent=1398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/categories?post=1398"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iuexterior.org\/ca\/wp-json\/wp\/v2\/tags?post=1398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}